{"id":34,"date":"2024-05-04T00:34:58","date_gmt":"2024-05-03T22:34:58","guid":{"rendered":"https:\/\/wadirumdune.com\/?page_id=34"},"modified":"2024-10-09T20:34:25","modified_gmt":"2024-10-09T18:34:25","slug":"nacht-in-der-wuste","status":"publish","type":"page","link":"https:\/\/wadirumdune.com\/de\/nacht-in-der-wuste\/","title":{"rendered":"Die Nacht in der W\u00fcste"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"34\" class=\"elementor elementor-34\" data-elementor-post-type=\"page\">\n\t\t\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-75b6213e e-flex e-con-boxed e-con e-parent\" data-id=\"75b6213e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-387b070e e-flex e-con-boxed e-con e-child\" data-id=\"387b070e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1b0f439c eael-dual-header-content-align-center elementor-invisible elementor-widget elementor-widget-eael-dual-color-header\" data-id=\"1b0f439c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"eael-dual-color-header.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"eael-dual-header\">\n\t\t\t\t<h1 class=\"title eael-dch-title\"><span class=\"eael-dch-title-text eael-dch-title-lead lead solid-color\">WADI RUM<\/span> <span class=\"eael-dch-title-text\">DUNE<\/span><\/h1>\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-19398948 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"19398948\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Tours &amp; Camp<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7c5c0c82 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"7c5c0c82\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ihr Beduinenabenteuer beginnt hier <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-34dd333a elementor-align-center elementor-invisible elementor-widget elementor-widget-button\" data-id=\"34dd333a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/wadirumdune.com\/de\/reservierung\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Buchen Sie Ihr Erlebnis<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-e5b0d5f e-flex e-con-boxed e-con e-parent\" data-id=\"e5b0d5f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bd9da40 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"bd9da40\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Nacht in der W\u00fcste<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-8da5506 e-con-full e-flex e-con e-child\" data-id=\"8da5506\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4b4badb elementor-widget-divider--view-line elementor-invisible elementor-widget elementor-widget-divider\" data-id=\"4b4badb\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:300}\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-f7b74e7 envato-kit-141-top-0 e-con-full e-flex e-con e-child\" data-id=\"f7b74e7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-cf77903 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"cf77903\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeIn&quot;,&quot;animation_delay&quot;:200}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-182361a elementor-widget elementor-widget-image\" data-id=\"182361a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/wadirumdune.com\/wp-content\/uploads\/elementor\/thumbs\/232107609-qqtfqfgphhp9hgvj0fuzwnn4x0kq19wazhow6pjc80.jpg\" title=\"232107609\" alt=\"232107609\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2817c94 elementor-widget elementor-widget-heading\" data-id=\"2817c94\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00dcbernachtung im Lager<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0c076b2 elementor-widget elementor-widget-text-editor\" data-id=\"0c076b2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Schlafen Sie in unserem Camp unter den Sternen der Wadi Rum-W\u00fcste. Genie\u00dfen Sie den Komfort und die Authentizit\u00e4t unserer Beduinenzelte.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4a17d8d elementor-align-center elementor-widget elementor-widget-button\" data-id=\"4a17d8d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#camp\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">mehr erfahren<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-b8ffa23 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"b8ffa23\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeIn&quot;,&quot;animation_delay&quot;:200}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-18e45b6 elementor-widget elementor-widget-image\" data-id=\"18e45b6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/wadirumdune.com\/wp-content\/uploads\/elementor\/thumbs\/IMG-20240529-WA0052-qqtfqfgphhp9hgvj0fuzwnn4x0kq19wazhow6pjc80.jpg\" title=\"IMG-20240529-WA0052\" alt=\"Nacht unter dem Sternenhimmel\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f8e8a5c elementor-widget elementor-widget-heading\" data-id=\"f8e8a5c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Nacht unter dem Sternenhimmel<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1b31f79 elementor-widget elementor-widget-text-editor\" data-id=\"1b31f79\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Erleben Sie eine magische Nacht unter dem Sternenhimmel von Wadi Rum und genie\u00dfen Sie die Ruhe der W\u00fcste und die W\u00e4rme eines Beduinenlagerfeuers.\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0722b90 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"0722b90\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#etoile\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">mehr erfahren<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-272b864 e-con-full e-flex e-con e-parent\" data-id=\"272b864\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-d808fb9 e-flex e-con-boxed e-con e-child\" data-id=\"d808fb9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ed342a0 elementor-widget elementor-widget-menu-anchor\" data-id=\"ed342a0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"camp\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0f252e9 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"0f252e9\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Nacht im CAMP<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8e942af elementor-widget-divider--view-line elementor-invisible elementor-widget elementor-widget-divider\" data-id=\"8e942af\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:300}\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-1f9b557 e-con-full e-flex e-con e-child\" data-id=\"1f9b557\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-1089ebd e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"1089ebd\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ae20367 elementor-widget elementor-widget-image\" data-id=\"ae20367\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"450\" src=\"https:\/\/wadirumdune.com\/wp-content\/uploads\/2024\/05\/491940816-1024x576.jpg\" class=\"attachment-large size-large wp-image-2027\" alt=\"Lager\" srcset=\"https:\/\/wadirumdune.com\/wp-content\/uploads\/2024\/05\/491940816-1024x576.jpg 1024w, https:\/\/wadirumdune.com\/wp-content\/uploads\/2024\/05\/491940816-600x338.jpg 600w, https:\/\/wadirumdune.com\/wp-content\/uploads\/2024\/05\/491940816-300x169.jpg 300w, https:\/\/wadirumdune.com\/wp-content\/uploads\/2024\/05\/491940816-768x432.jpg 768w, https:\/\/wadirumdune.com\/wp-content\/uploads\/2024\/05\/491940816-800x450.jpg 800w, https:\/\/wadirumdune.com\/wp-content\/uploads\/2024\/05\/491940816.jpg 1280w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-35aaab1 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"35aaab1\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c5288c9 elementor-widget elementor-widget-text-editor\" data-id=\"c5288c9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"flex flex-grow flex-col max-w-full\"><div class=\"min-h-[20px] text-message flex flex-col items-start whitespace-pre-wrap break-words [.text-message+&amp;]:mt-5 juice:w-full juice:items-end overflow-x-auto gap-3\" dir=\"auto\" data-message-author-role=\"assistant\" data-message-id=\"5b2ba6a3-4ca0-4d8d-bfbf-71ea50b6e6ed\"><div class=\"markdown prose w-full break-words dark:prose-invert dark\"><p>Schlafen Sie in unserem Camp unter den Sternen der Wadi Rum-W\u00fcste. Genie\u00dfen Sie den Komfort und die Authentizit\u00e4t unserer Beduinenzelte, die f\u00fcr ein einzigartiges Campingerlebnis ausgestattet sind. Erleben Sie den Zauber der W\u00fcste und wachen Sie mit dem Sonnenaufgang \u00fcber dieser legend\u00e4ren Landschaft auf.<\/p><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5dec2e1 elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"5dec2e1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-map-marker-alt\" viewbox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M172.268 501.67C26.97 291.031 0 269.413 0 192 0 85.961 85.961 0 192 0s192 85.961 192 192c0 77.413-26.97 99.031-172.268 309.67-9.535 13.774-29.93 13.773-39.464 0zM192 272c44.183 0 80-35.817 80-80s-35.817-80-80-80-80 35.817-80 80 35.817 80 80 80z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><span><b><font style=\"vertical-align: inherit\"><font style=\"vertical-align: inherit\">Lokalisierung:<\/font><\/font><\/b><font style=\"vertical-align: inherit\"><font style=\"vertical-align: inherit\"> <\/font><\/font><\/span><span style=\"font-size: 12pt;line-height: 107%;font-family: Oswald;background-image: initial;background-position: initial;background-size: initial;background-repeat: initial;background-attachment: initial\">Unser Camp liegt 12 km vom Dorf Wadi Rum entfernt und geh\u00f6rt zu den wenigen inmitten der W\u00fcste.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-truck-pickup\" viewbox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M624 288h-16v-64c0-17.67-14.33-32-32-32h-48L419.22 56.02A64.025 64.025 0 0 0 369.24 32H256c-17.67 0-32 14.33-32 32v128H64c-17.67 0-32 14.33-32 32v64H16c-8.84 0-16 7.16-16 16v32c0 8.84 7.16 16 16 16h49.61c-.76 5.27-1.61 10.52-1.61 16 0 61.86 50.14 112 112 112s112-50.14 112-112c0-5.48-.85-10.73-1.61-16h67.23c-.76 5.27-1.61 10.52-1.61 16 0 61.86 50.14 112 112 112s112-50.14 112-112c0-5.48-.85-10.73-1.61-16H624c8.84 0 16-7.16 16-16v-32c0-8.84-7.16-16-16-16zM288 96h81.24l76.8 96H288V96zM176 416c-26.47 0-48-21.53-48-48s21.53-48 48-48 48 21.53 48 48-21.53 48-48 48zm288 0c-26.47 0-48-21.53-48-48s21.53-48 48-48 48 21.53 48 48-21.53 48-48 48z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><span><b><font style=\"vertical-align: inherit\"><font style=\"vertical-align: inherit\">Transport <\/font><\/font><\/b><font style=\"vertical-align: inherit\"><font style=\"vertical-align: inherit\">: <\/font><\/font><\/span><span data-elementor-setting-key=\"icon_list.0.text\" data-pen-placeholder=\"\u00c9crivez ici...\"><\/span><br><span><font style=\"vertical-align: inherit\"><font style=\"vertical-align: inherit\">- <\/font><\/font><\/span><span data-elementor-setting-key=\"icon_list.5.text\" data-pen-placeholder=\"\u00c9crivez ici...\"><span style=\"font-size: 12pt;line-height: 107%;font-family: Oswald;background-image: initial;background-position: initial;background-size: initial;background-repeat: initial;background-attachment: initial\">Nach einem Ausflug werden Sie direkt im Lager abgesetzt<\/span><\/span><br><span><font style=\"vertical-align: inherit\"><font style=\"vertical-align: inherit\">- <\/font><\/font><\/span><span data-elementor-setting-key=\"icon_list.5.text\" data-pen-placeholder=\"\u00c9crivez ici...\"><span style=\"font-size: 12pt;color: var( --e-global-color-secondary );background-image: initial;background-position: initial;background-size: initial;background-repeat: initial;background-attachment: initial;line-height: 107%;font-family: Oswald\">Andernfalls holen wir Sie im Dorf Wadi Rum ab.<\/span><\/span><span><font style=\"vertical-align: inherit\"><font style=\"vertical-align: inherit\">.<\/font><\/font><\/span><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-campground\" viewbox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M624 448h-24.68L359.54 117.75l53.41-73.55c5.19-7.15 3.61-17.16-3.54-22.35l-25.9-18.79c-7.15-5.19-17.15-3.61-22.35 3.55L320 63.3 278.83 6.6c-5.19-7.15-15.2-8.74-22.35-3.55l-25.88 18.8c-7.15 5.19-8.74 15.2-3.54 22.35l53.41 73.55L40.68 448H16c-8.84 0-16 7.16-16 16v32c0 8.84 7.16 16 16 16h608c8.84 0 16-7.16 16-16v-32c0-8.84-7.16-16-16-16zM320 288l116.36 160H203.64L320 288z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><span><b><font style=\"vertical-align: inherit\"><font style=\"vertical-align: inherit\">Das Lager : <\/font><\/font><\/b> <\/span><span style=\"font-size: 12pt;line-height: 107%;font-family: Oswald;background-image: initial;background-position: initial;background-size: initial;background-repeat: initial;background-attachment: initial\"> von \u00fcberschaubarer Gr\u00f6\u00dfe, bietet Platz f\u00fcr bis zu 25 Personen. <\/span><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-bed\" viewbox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M176 256c44.11 0 80-35.89 80-80s-35.89-80-80-80-80 35.89-80 80 35.89 80 80 80zm352-128H304c-8.84 0-16 7.16-16 16v144H64V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v352c0 8.84 7.16 16 16 16h32c8.84 0 16-7.16 16-16v-48h512v48c0 8.84 7.16 16 16 16h32c8.84 0 16-7.16 16-16V240c0-61.86-50.14-112-112-112z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><span><b><font style=\"vertical-align: inherit\"><font style=\"vertical-align: inherit\">Zelt &amp; Betten :<\/font><\/font><\/b> <\/span><span><font style=\"vertical-align: inherit\"><font style=\"vertical-align: inherit\"> <\/font><\/font><\/span><span style=\"font-size: 12pt;line-height: 107%;font-family: Oswald;background-image: initial;background-position: initial;background-size: initial;background-repeat: initial;background-attachment: initial\">Das Camp hat 15 private Zelte und es gibt zwischen 2 und 5 Betten in jedem Zelt. <\/span><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-shower\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M304,320a16,16,0,1,0,16,16A16,16,0,0,0,304,320Zm32-96a16,16,0,1,0,16,16A16,16,0,0,0,336,224Zm32,64a16,16,0,1,0-16-16A16,16,0,0,0,368,288Zm-32,32a16,16,0,1,0-16-16A16,16,0,0,0,336,320Zm-32-64a16,16,0,1,0,16,16A16,16,0,0,0,304,256Zm128-32a16,16,0,1,0-16-16A16,16,0,0,0,432,224Zm-48,16a16,16,0,1,0,16-16A16,16,0,0,0,384,240Zm-16-48a16,16,0,1,0,16,16A16,16,0,0,0,368,192Zm96,32a16,16,0,1,0,16,16A16,16,0,0,0,464,224Zm32-32a16,16,0,1,0,16,16A16,16,0,0,0,496,192Zm-64,64a16,16,0,1,0,16,16A16,16,0,0,0,432,256Zm-32,32a16,16,0,1,0,16,16A16,16,0,0,0,400,288Zm-64,64a16,16,0,1,0,16,16A16,16,0,0,0,336,352Zm-32,32a16,16,0,1,0,16,16A16,16,0,0,0,304,384Zm64-64a16,16,0,1,0,16,16A16,16,0,0,0,368,320Zm21.65-218.35-11.3-11.31a16,16,0,0,0-22.63,0L350.05,96A111.19,111.19,0,0,0,272,64c-19.24,0-37.08,5.3-52.9,13.85l-10-10A121.72,121.72,0,0,0,123.44,32C55.49,31.5,0,92.91,0,160.85V464a16,16,0,0,0,16,16H48a16,16,0,0,0,16-16V158.4c0-30.15,21-58.2,51-61.93a58.38,58.38,0,0,1,48.93,16.67l10,10C165.3,138.92,160,156.76,160,176a111.23,111.23,0,0,0,32,78.05l-5.66,5.67a16,16,0,0,0,0,22.62l11.3,11.31a16,16,0,0,0,22.63,0L389.65,124.28A16,16,0,0,0,389.65,101.65Z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><span><b><font style=\"vertical-align: inherit\"><font style=\"vertical-align: inherit\">Badezimmer : <\/font><\/font><\/b><\/span><span style=\"font-size: 12pt;line-height: 107%;font-family: Oswald;background-image: initial;background-position: initial;background-size: initial;background-repeat: initial;background-attachment: initial\">Die Badezimmer sind gemeinschaftlich, mit 4 westlichen Toiletten und 4 Duschen mit Warmwasser. Zelte mit eigenem Bad werden in begrenzter Anzahl angeboten. <\/span><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-utensils\" viewbox=\"0 0 416 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.9 15.2c.8 4.7 16.1 94.5 16.1 128.8 0 52.3-27.8 89.6-68.9 104.6L168 486.7c.7 13.7-10.2 25.3-24 25.3H80c-13.7 0-24.7-11.5-24-25.3l12.9-238.1C27.7 233.6 0 196.2 0 144 0 109.6 15.3 19.9 16.1 15.2 19.3-5.1 61.4-5.4 64 16.3v141.2c1.3 3.4 15.1 3.2 16 0 1.4-25.3 7.9-139.2 8-141.8 3.3-20.8 44.7-20.8 47.9 0 .2 2.7 6.6 116.5 8 141.8.9 3.2 14.8 3.4 16 0V16.3c2.6-21.6 44.8-21.4 48-1.1zm119.2 285.7l-15 185.1c-1.2 14 9.9 26 23.9 26h56c13.3 0 24-10.7 24-24V24c0-13.2-10.7-24-24-24-82.5 0-221.4 178.5-64.9 300.9z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><span><b><font style=\"vertical-align: inherit\"><font style=\"vertical-align: inherit\">Essen:<\/font><\/font><\/b><\/span><span style=\"font-size: 12pt;line-height: 107%;font-family: Oswald;background-image: initial;background-position: initial;background-size: initial;background-repeat: initial;background-attachment: initial\"> Halbpension Ein Beduinen-Abendessen und ein Fr\u00fchst\u00fcck sind in unserem Service inbegriffen <\/span><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plug\" viewbox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M320,32a32,32,0,0,0-64,0v96h64Zm48,128H16A16,16,0,0,0,0,176v32a16,16,0,0,0,16,16H32v32A160.07,160.07,0,0,0,160,412.8V512h64V412.8A160.07,160.07,0,0,0,352,256V224h16a16,16,0,0,0,16-16V176A16,16,0,0,0,368,160ZM128,32a32,32,0,0,0-64,0v96h64Z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><span><b><font style=\"vertical-align: inherit\"><font style=\"vertical-align: inherit\">Ausstattung :<\/font><\/font><\/b> <\/span><span style=\"font-size: 12pt;line-height: 107%;font-family: Oswald;background-image: initial;background-position: initial;background-size: initial;background-repeat: initial;background-attachment: initial\">Die Zelte sind mit elektrischer Beleuchtung und Steckdosen zum Aufladen Ihrer elektronischen Ger\u00e4te ausgestattet.<\/span><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9e04eee e-n-tabs-mobile elementor-invisible elementor-widget elementor-widget-n-tabs\" data-id=\"9e04eee\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;horizontal_scroll&quot;:&quot;disable&quot;}\" data-widget_type=\"nested-tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-tabs\" data-widget-number=\"165695214\" aria-label=\"Tabs. Open items with Enter or Space, close with Escape and navigate using the Arrow keys.\">\n\t\t\t<div class=\"e-n-tabs-heading\" role=\"tablist\">\n\t\t\t\t\t<button id=\"e-n-tab-title-1656952141\" data-tab-title-id=\"e-n-tab-title-1656952141\" class=\"e-n-tab-title\" aria-selected=\"true\" data-tab-index=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"e-n-tab-content-1656952141\" style=\"--n-tabs-title-order: 1;\">\n\t\t\t\t\t<span class=\"e-n-tab-icon\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-exclamation-triangle\" viewbox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M569.517 440.013C587.975 472.007 564.806 512 527.94 512H48.054c-36.937 0-59.999-40.055-41.577-71.987L246.423 23.985c18.467-32.009 64.72-31.951 83.154 0l239.94 416.028zM288 354c-25.405 0-46 20.595-46 46s20.595 46 46 46 46-20.595 46-46-20.595-46-46-46zm-43.673-165.346l7.418 136c.347 6.364 5.609 11.346 11.982 11.346h48.546c6.373 0 11.635-4.982 11.982-11.346l7.418-136c.375-6.874-5.098-12.654-11.982-12.654h-63.383c-6.884 0-12.356 5.78-11.981 12.654z\"><\/path><\/svg>\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-exclamation-triangle\" viewbox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M569.517 440.013C587.975 472.007 564.806 512 527.94 512H48.054c-36.937 0-59.999-40.055-41.577-71.987L246.423 23.985c18.467-32.009 64.72-31.951 83.154 0l239.94 416.028zM288 354c-25.405 0-46 20.595-46 46s20.595 46 46 46 46-20.595 46-46-20.595-46-46-46zm-43.673-165.346l7.418 136c.347 6.364 5.609 11.346 11.982 11.346h48.546c6.373 0 11.635-4.982 11.982-11.346l7.418-136c.375-6.874-5.098-12.654-11.982-12.654h-63.383c-6.884 0-12.356 5.78-11.981 12.654z\"><\/path><\/svg>\t\t<\/span>\n\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\tWICHTIG ZU WISSEN\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t<button id=\"e-n-tab-title-1656952142\" data-tab-title-id=\"e-n-tab-title-1656952142\" class=\"e-n-tab-title\" aria-selected=\"false\" data-tab-index=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"e-n-tab-content-1656952142\" style=\"--n-tabs-title-order: 2;\">\n\t\t\t\t\t<span class=\"e-n-tab-icon\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-truck-pickup\" viewbox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M624 288h-16v-64c0-17.67-14.33-32-32-32h-48L419.22 56.02A64.025 64.025 0 0 0 369.24 32H256c-17.67 0-32 14.33-32 32v128H64c-17.67 0-32 14.33-32 32v64H16c-8.84 0-16 7.16-16 16v32c0 8.84 7.16 16 16 16h49.61c-.76 5.27-1.61 10.52-1.61 16 0 61.86 50.14 112 112 112s112-50.14 112-112c0-5.48-.85-10.73-1.61-16h67.23c-.76 5.27-1.61 10.52-1.61 16 0 61.86 50.14 112 112 112s112-50.14 112-112c0-5.48-.85-10.73-1.61-16H624c8.84 0 16-7.16 16-16v-32c0-8.84-7.16-16-16-16zM288 96h81.24l76.8 96H288V96zM176 416c-26.47 0-48-21.53-48-48s21.53-48 48-48 48 21.53 48 48-21.53 48-48 48zm288 0c-26.47 0-48-21.53-48-48s21.53-48 48-48 48 21.53 48 48-21.53 48-48 48z\"><\/path><\/svg>\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-truck-pickup\" viewbox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M624 288h-16v-64c0-17.67-14.33-32-32-32h-48L419.22 56.02A64.025 64.025 0 0 0 369.24 32H256c-17.67 0-32 14.33-32 32v128H64c-17.67 0-32 14.33-32 32v64H16c-8.84 0-16 7.16-16 16v32c0 8.84 7.16 16 16 16h49.61c-.76 5.27-1.61 10.52-1.61 16 0 61.86 50.14 112 112 112s112-50.14 112-112c0-5.48-.85-10.73-1.61-16h67.23c-.76 5.27-1.61 10.52-1.61 16 0 61.86 50.14 112 112 112s112-50.14 112-112c0-5.48-.85-10.73-1.61-16H624c8.84 0 16-7.16 16-16v-32c0-8.84-7.16-16-16-16zM288 96h81.24l76.8 96H288V96zM176 416c-26.47 0-48-21.53-48-48s21.53-48 48-48 48 21.53 48 48-21.53 48-48 48zm288 0c-26.47 0-48-21.53-48-48s21.53-48 48-48 48 21.53 48 48-21.53 48-48 48z\"><\/path><\/svg>\t\t<\/span>\n\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\tTRANSPORT\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t<button id=\"e-n-tab-title-1656952143\" data-tab-title-id=\"e-n-tab-title-1656952143\" class=\"e-n-tab-title\" aria-selected=\"false\" data-tab-index=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"e-n-tab-content-1656952143\" style=\"--n-tabs-title-order: 3;\">\n\t\t\t\t\t<span class=\"e-n-tab-icon\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plug\" viewbox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M320,32a32,32,0,0,0-64,0v96h64Zm48,128H16A16,16,0,0,0,0,176v32a16,16,0,0,0,16,16H32v32A160.07,160.07,0,0,0,160,412.8V512h64V412.8A160.07,160.07,0,0,0,352,256V224h16a16,16,0,0,0,16-16V176A16,16,0,0,0,368,160ZM128,32a32,32,0,0,0-64,0v96h64Z\"><\/path><\/svg>\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plug\" viewbox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M320,32a32,32,0,0,0-64,0v96h64Zm48,128H16A16,16,0,0,0,0,176v32a16,16,0,0,0,16,16H32v32A160.07,160.07,0,0,0,160,412.8V512h64V412.8A160.07,160.07,0,0,0,352,256V224h16a16,16,0,0,0,16-16V176A16,16,0,0,0,368,160ZM128,32a32,32,0,0,0-64,0v96h64Z\"><\/path><\/svg>\t\t<\/span>\n\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\tUNSERE EINRICHTUNGEN\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t<button id=\"e-n-tab-title-1656952144\" data-tab-title-id=\"e-n-tab-title-1656952144\" class=\"e-n-tab-title\" aria-selected=\"false\" data-tab-index=\"4\" role=\"tab\" tabindex=\"-1\" aria-controls=\"e-n-tab-content-1656952144\" style=\"--n-tabs-title-order: 4;\">\n\t\t\t\t\t<span class=\"e-n-tab-icon\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-utensils\" viewbox=\"0 0 416 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.9 15.2c.8 4.7 16.1 94.5 16.1 128.8 0 52.3-27.8 89.6-68.9 104.6L168 486.7c.7 13.7-10.2 25.3-24 25.3H80c-13.7 0-24.7-11.5-24-25.3l12.9-238.1C27.7 233.6 0 196.2 0 144 0 109.6 15.3 19.9 16.1 15.2 19.3-5.1 61.4-5.4 64 16.3v141.2c1.3 3.4 15.1 3.2 16 0 1.4-25.3 7.9-139.2 8-141.8 3.3-20.8 44.7-20.8 47.9 0 .2 2.7 6.6 116.5 8 141.8.9 3.2 14.8 3.4 16 0V16.3c2.6-21.6 44.8-21.4 48-1.1zm119.2 285.7l-15 185.1c-1.2 14 9.9 26 23.9 26h56c13.3 0 24-10.7 24-24V24c0-13.2-10.7-24-24-24-82.5 0-221.4 178.5-64.9 300.9z\"><\/path><\/svg>\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-utensils\" viewbox=\"0 0 416 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.9 15.2c.8 4.7 16.1 94.5 16.1 128.8 0 52.3-27.8 89.6-68.9 104.6L168 486.7c.7 13.7-10.2 25.3-24 25.3H80c-13.7 0-24.7-11.5-24-25.3l12.9-238.1C27.7 233.6 0 196.2 0 144 0 109.6 15.3 19.9 16.1 15.2 19.3-5.1 61.4-5.4 64 16.3v141.2c1.3 3.4 15.1 3.2 16 0 1.4-25.3 7.9-139.2 8-141.8 3.3-20.8 44.7-20.8 47.9 0 .2 2.7 6.6 116.5 8 141.8.9 3.2 14.8 3.4 16 0V16.3c2.6-21.6 44.8-21.4 48-1.1zm119.2 285.7l-15 185.1c-1.2 14 9.9 26 23.9 26h56c13.3 0 24-10.7 24-24V24c0-13.2-10.7-24-24-24-82.5 0-221.4 178.5-64.9 300.9z\"><\/path><\/svg>\t\t<\/span>\n\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\tUNSERE MAHLZEITEN\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t<button id=\"e-n-tab-title-1656952145\" data-tab-title-id=\"e-n-tab-title-1656952145\" class=\"e-n-tab-title\" aria-selected=\"false\" data-tab-index=\"5\" role=\"tab\" tabindex=\"-1\" aria-controls=\"e-n-tab-content-1656952145\" style=\"--n-tabs-title-order: 5;\">\n\t\t\t\t\t<span class=\"e-n-tab-icon\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-bed\" viewbox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M176 256c44.11 0 80-35.89 80-80s-35.89-80-80-80-80 35.89-80 80 35.89 80 80 80zm352-128H304c-8.84 0-16 7.16-16 16v144H64V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v352c0 8.84 7.16 16 16 16h32c8.84 0 16-7.16 16-16v-48h512v48c0 8.84 7.16 16 16 16h32c8.84 0 16-7.16 16-16V240c0-61.86-50.14-112-112-112z\"><\/path><\/svg>\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-bed\" viewbox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M176 256c44.11 0 80-35.89 80-80s-35.89-80-80-80-80 35.89-80 80 35.89 80 80 80zm352-128H304c-8.84 0-16 7.16-16 16v144H64V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v352c0 8.84 7.16 16 16 16h32c8.84 0 16-7.16 16-16v-48h512v48c0 8.84 7.16 16 16 16h32c8.84 0 16-7.16 16-16V240c0-61.86-50.14-112-112-112z\"><\/path><\/svg>\t\t<\/span>\n\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\tUNSERE ZELTE\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t\t<\/div>\n\t\t\t<div class=\"e-n-tabs-content\">\n\t\t\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" id=\"e-n-tab-content-1656952141\" role=\"tabpanel\" aria-labelledby=\"e-n-tab-title-1656952141\" data-tab-index=\"1\" style=\"--n-tabs-title-order: 1;\" class=\"e-active elementor-element elementor-element-b7e9087 e-con-full e-flex e-con e-child\" data-id=\"b7e9087\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-b19a09b e-con-full e-flex e-con e-child\" data-id=\"b19a09b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1f27e85 elementor-widget elementor-widget-image\" data-id=\"1f27e85\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"1024\" src=\"https:\/\/wadirumdune.com\/wp-content\/uploads\/2024\/05\/sebastian-leonhardt-0t_RxCwoYSI-unsplash-scaled-e1715042109970-800x1024.jpg\" class=\"attachment-large size-large wp-image-91\" alt=\"\" srcset=\"https:\/\/wadirumdune.com\/wp-content\/uploads\/2024\/05\/sebastian-leonhardt-0t_RxCwoYSI-unsplash-scaled-e1715042109970-800x1024.jpg 800w, https:\/\/wadirumdune.com\/wp-content\/uploads\/2024\/05\/sebastian-leonhardt-0t_RxCwoYSI-unsplash-scaled-e1715042109970-600x768.jpg 600w, https:\/\/wadirumdune.com\/wp-content\/uploads\/2024\/05\/sebastian-leonhardt-0t_RxCwoYSI-unsplash-scaled-e1715042109970-234x300.jpg 234w, https:\/\/wadirumdune.com\/wp-content\/uploads\/2024\/05\/sebastian-leonhardt-0t_RxCwoYSI-unsplash-scaled-e1715042109970-768x983.jpg 768w, https:\/\/wadirumdune.com\/wp-content\/uploads\/2024\/05\/sebastian-leonhardt-0t_RxCwoYSI-unsplash-scaled-e1715042109970-1200x1536.jpg 1200w, https:\/\/wadirumdune.com\/wp-content\/uploads\/2024\/05\/sebastian-leonhardt-0t_RxCwoYSI-unsplash-scaled-e1715042109970-1600x2048.jpg 1600w, https:\/\/wadirumdune.com\/wp-content\/uploads\/2024\/05\/sebastian-leonhardt-0t_RxCwoYSI-unsplash-scaled-e1715042109970.jpg 1706w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-56c8d8b e-con-full e-flex e-con e-child\" data-id=\"56c8d8b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-da1e1c0 elementor-widget elementor-widget-text-editor\" data-id=\"da1e1c0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3><span style=\"color: #000000;\">Ankunft Abreise<\/span><\/h3><ul><li>Der Treffpunkt ist in <a href=\"https:\/\/maps.app.goo.gl\/aXbaKEQfBJAzXijX9\" target=\"_blank\" rel=\"noopener\">Wadi Rum Rest House<\/a>.<\/li><li>Der Check-in findet bei Sonnenuntergang statt (18:00-19:00 Uhr im Sommer oder 17:00-18:00 Uhr im Winter).<\/li><li>Die Abfahrtszeit ist um 8:30 Uhr.<\/li><li>Wenn Sie mit dem Taxi anreisen, bitten Sie den Fahrer, Sie am Treffpunkt (oben angegeben) abzusetzen. Wenn Sie mit dem Privatwagen anreisen, k\u00f6nnen Sie auf dem kostenlosen Parkplatz in <a href=\"https:\/\/maps.app.goo.gl\/aXbaKEQfBJAzXijX9\" target=\"_blank\" rel=\"noopener\">Wadi Rum Rest House<\/a>.<\/li><li>Wir bringen Sie zum Zeitpunkt der Abreise zur\u00fcck ins Dorf.<\/li><li>Wir k\u00f6nnen Ihnen helfen, eine Transportm\u00f6glichkeit zu Ihrem n\u00e4chsten Ziel zu finden (mit dem Taxi oder Bus).<\/li><\/ul><h3><span style=\"color: #000000;\">Essen<\/span><\/h3><ul><li>Das Abendessen beginnt um 19.00 Uhr.<\/li><li>\u00a0Das Fr\u00fchst\u00fcck beginnt um 7.00 Uhr.<\/li><li>\u00a0Wir servieren traditionelle Beduinengerichte, Zarb (unter dem Sand gebratenes Huhn und Gem\u00fcse) oder Sinea (Rindfleisch oder Huhn mit Gem\u00fcse im Topf) mit Reis, arabischen Salaten und Brot. Mansaf, das jordanische Nationalgericht, kann auf Wunsch zubereitet werden.<\/li><li>Auch das Fr\u00fchst\u00fcck ist im traditionellen Beduinenstil gehalten und beinhaltet Hummus, Halawa (s\u00fc\u00dfe Pistazienpaste), Eier, Bohnen, K\u00e4se, Marmelade, Kekse und Tee oder Kaffee.<\/li><li>vegetarische Gerichte sind auf Anfrage erh\u00e4ltlich, obwohl die traditionelle Beduinenk\u00fcche ohnehin gr\u00f6\u00dftenteils vegetarisch\/vegan ist, so dass immer auch fleischlose Optionen verf\u00fcgbar sind. Bitte informieren Sie uns bei der Buchung und bei Ihrer Ankunft (nur um uns daran zu erinnern!), wenn Sie besondere Ern\u00e4hrungsbed\u00fcrfnisse haben.<\/li><\/ul><h3><span style=\"color: #000000;\">Im Preis inbegriffen<\/span><\/h3><ul><li>Abendessen\/Fr\u00fchst\u00fcck.<\/li><li>Kaffee\/Tee\/Wasser.<\/li><\/ul><h3><span style=\"color: #000000;\">Vom Preis ausgeschlossen<\/span><\/h3><ul><li>Eintrittsgeb\u00fchr f\u00fcr das Wadi Rum (7 JOD).<\/li><li>\u00a0jordan pass<\/li><\/ul><p>Wenn Sie \u00fcber Nacht bleiben m\u00f6chten, ohne einen Ausflug zu buchen, wird Ihnen der Transfer vom Dorf Wadi Rum zum Camp zus\u00e4tzlich berechnet. F\u00fcr weitere Details k\u00f6nnen Sie sich direkt mit uns in Verbindung setzen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" id=\"e-n-tab-content-1656952142\" role=\"tabpanel\" aria-labelledby=\"e-n-tab-title-1656952142\" data-tab-index=\"2\" style=\"--n-tabs-title-order: 2;\" class=\"elementor-element elementor-element-2e9b940 e-con-full e-flex e-con e-child\" data-id=\"2e9b940\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-4ddaa1e e-con-full e-flex e-con e-child\" data-id=\"4ddaa1e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2593dbc elementor-widget elementor-widget-image\" data-id=\"2593dbc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"450\" src=\"https:\/\/wadirumdune.com\/wp-content\/uploads\/2024\/05\/GH012022_1715447437971-1024x576.jpg\" class=\"attachment-large size-large wp-image-1444\" alt=\"Jeep 4x4-Touren\" srcset=\"https:\/\/wadirumdune.com\/wp-content\/uploads\/2024\/05\/GH012022_1715447437971-1024x576.jpg 1024w, https:\/\/wadirumdune.com\/wp-content\/uploads\/2024\/05\/GH012022_1715447437971-600x338.jpg 600w, https:\/\/wadirumdune.com\/wp-content\/uploads\/2024\/05\/GH012022_1715447437971-300x169.jpg 300w, https:\/\/wadirumdune.com\/wp-content\/uploads\/2024\/05\/GH012022_1715447437971-768x432.jpg 768w, https:\/\/wadirumdune.com\/wp-content\/uploads\/2024\/05\/GH012022_1715447437971-1536x864.jpg 1536w, https:\/\/wadirumdune.com\/wp-content\/uploads\/2024\/05\/GH012022_1715447437971-800x450.jpg 800w, https:\/\/wadirumdune.com\/wp-content\/uploads\/2024\/05\/GH012022_1715447437971.jpg 1920w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-29caae0 e-con-full e-flex e-con e-child\" data-id=\"29caae0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-68862fa elementor-widget elementor-widget-text-editor\" data-id=\"68862fa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\"><span class=\"elementor-icon-list-text elementor-inline-editing pen\" contenteditable=\"true\" data-elementor-setting-key=\"icon_list.0.text\" data-pen-placeholder=\"\u00c9crivez ici...\">Unser Lager liegt 12 km vom Dorf Wadi Rum entfernt. Unser Lager ist eines der wenigen inmitten der W\u00fcste, und es gibt folgende M\u00f6glichkeiten, zu unserem Lager zu gelangen:<br \/><\/span><\/p><ul><li><span class=\"elementor-icon-list-text elementor-inline-editing pen\" contenteditable=\"true\" data-elementor-setting-key=\"icon_list.1.text\" data-pen-placeholder=\"\u00c9crivez ici...\"><span contenteditable=\"true\" data-elementor-setting-key=\"icon_list.5.text\" data-pen-placeholder=\"\u00c9crivez ici...\">wenn Sie einen Ausflug bei uns gebucht haben, Ihr Transfer<\/span> vom Wadi Rum Village zum Camp ist in unseren Ausfl\u00fcgen enthalten<br \/><\/span><\/li><li>Wenn Sie keinen Ausflug machen, wird Ihnen der Transfer vom Wadi Rum Village zum Camp zus\u00e4tzlich berechnet.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" id=\"e-n-tab-content-1656952143\" role=\"tabpanel\" aria-labelledby=\"e-n-tab-title-1656952143\" data-tab-index=\"3\" style=\"--n-tabs-title-order: 3;\" class=\"elementor-element elementor-element-45c2d4f e-con-full e-flex e-con e-child\" data-id=\"45c2d4f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-938e977 e-con-full e-flex e-con e-child\" data-id=\"938e977\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c75f274 elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"c75f274\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Bild Karussell\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 von 8\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/wadirumdune.com\/wp-content\/uploads\/2024\/05\/Cropped_Image-1.jpg\" alt=\"Cropped_Image\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 von 8\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/wadirumdune.com\/wp-content\/uploads\/2024\/05\/Image_Editor-1.jpg\" alt=\"Image_Editor (1)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 von 8\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/wadirumdune.com\/wp-content\/uploads\/2024\/05\/Image_Editor-15.jpg\" alt=\"Image_Editor (15)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 von 8\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/wadirumdune.com\/wp-content\/uploads\/2024\/05\/Image_Editor.jpg\" alt=\"Image_Editor\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 von 8\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/wadirumdune.com\/wp-content\/uploads\/2024\/05\/Cropped_Image-2.jpg\" alt=\"Cropped_Image (2)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 von 8\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/wadirumdune.com\/wp-content\/uploads\/2024\/05\/Image_Editor1.jpg\" alt=\"Image_Editor(1)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 von 8\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/wadirumdune.com\/wp-content\/uploads\/2024\/05\/Image_Editor2.jpg\" alt=\"Image_Editor(2)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 von 8\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/wadirumdune.com\/wp-content\/uploads\/2024\/05\/Image_Editor-8.jpg\" alt=\"Image_Editor\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-875e666 e-con-full e-flex e-con e-child\" data-id=\"875e666\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1e00181 elementor-widget elementor-widget-text-editor\" data-id=\"1e00181\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3>Unterkunft<\/h3><ul><li>Zelte mit <span style=\"text-decoration: underline;\"><strong>eigenes Badezimmer<\/strong><\/span><\/li><li>Zelt mit Gemeinschaftsbad<\/li><li>die Zelte sind nicht klimatisiert<\/li><\/ul><h3>Sanit\u00e4re Einrichtungen<\/h3><p>Wir verf\u00fcgen \u00fcber moderne sanit\u00e4re Einrichtungen, einschlie\u00dflich Warmwasserduschen und sauberen Toiletten, um Ihren Komfort w\u00e4hrend Ihres Aufenthalts zu gew\u00e4hrleisten. vergessen Sie nicht, Ihre Handt\u00fccher mitzubringen.<\/p><ul><li><span class=\"elementor-icon-list-text elementor-inline-editing pen\" contenteditable=\"true\" data-elementor-setting-key=\"icon_list.4.text\" data-pen-placeholder=\"\u00c9crivez ici...\"><span lang=\"FR\">4 <\/span><span lang=\"FR\">westliche Toiletten und 4 Duschen mit hei\u00dfem Wasser, das nicht gemischt ist<\/span><\/span><\/li><\/ul><h3>Das zentrale Zelt<\/h3><p>Ein gro\u00dfes Zelt mit Teppichen, R\u00e4ucherst\u00e4bchen und einem knisternden Feuer dient als Gemeinschaftsraum, in dem wir Fr\u00fchst\u00fcck, Abendessen und Erfrischungen servieren. In w\u00e4rmeren N\u00e4chten wird das Feuer zu einer Feuerstelle im Freien verlegt, die von St\u00fchlen und Teppichen umgeben ist, wo man sitzen und den flackernden Flammen in der Dunkelheit der W\u00fcste zusehen kann.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" id=\"e-n-tab-content-1656952144\" role=\"tabpanel\" aria-labelledby=\"e-n-tab-title-1656952144\" data-tab-index=\"4\" style=\"--n-tabs-title-order: 4;\" class=\"elementor-element elementor-element-de0a1a0 e-con-full e-flex e-con e-child\" data-id=\"de0a1a0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-b1d8ff9 e-con-full e-flex e-con e-child\" data-id=\"b1d8ff9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ce4bf50 elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"ce4bf50\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Bild Karussell\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 von 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/wadirumdune.com\/wp-content\/uploads\/2024\/05\/Image_Editor-2.jpg\" alt=\"Image_Editor (2)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 von 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/wadirumdune.com\/wp-content\/uploads\/2024\/05\/IMG-20240509-WA0029.jpg\" alt=\"IMG-20240509-WA0029\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 von 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/wadirumdune.com\/wp-content\/uploads\/2024\/05\/Cropped_Image-1-1.jpg\" alt=\"Cropped_Image (1)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 von 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/wadirumdune.com\/wp-content\/uploads\/2024\/05\/Cropped_Image-8.jpg\" alt=\"Cropped_Image (8)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 von 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/wadirumdune.com\/wp-content\/uploads\/2024\/05\/Cropped_Image14.jpg\" alt=\"Cropped_Image(14)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 von 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/wadirumdune.com\/wp-content\/uploads\/2024\/05\/Cropped_Image15.jpg\" alt=\"Cropped_Image(15)\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-ec893ff e-con-full e-flex e-con e-child\" data-id=\"ec893ff\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a43b776 elementor-widget elementor-widget-text-editor\" data-id=\"a43b776\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Unser Camp bietet traditionelle Mahlzeiten, die sorgf\u00e4ltig zubereitet werden. Beginnen Sie Ihren Tag mit einem Beduinenfr\u00fchst\u00fcck, genie\u00dfen Sie ein leichtes Mittagessen und beenden Sie ihn mit einem Abendessen unter dem Sternenhimmel, das typische Gerichte wie Zarb beinhaltet, das nach althergebrachten Methoden unter der Erde gegart wird.<\/p><p><span style=\"text-decoration: underline; color: #000000;\"><strong>Abendessen:<\/strong><\/span> Entdecken Sie Zarb, das ikonische Gericht der W\u00fcste. Zarb wird langsam unter der Erde in einem Sandofen gekocht, was ihm reiche und k\u00f6stliche Aromen verleiht.<\/p><p>Schlie\u00dfen Sie sich uns am Lagerfeuer an, wo unsere beduinischen Gastgeber Sie mit duftendem Kardamomtee und faszinierenden Erz\u00e4hlungen \u00fcber die Kultur und Geschichte der W\u00fcste begr\u00fc\u00dfen werden. Das Essen beginnt mit einer Auswahl an Mezze, gefolgt von Zarb, das aus zartem Fleisch, schmackhaftem Gem\u00fcse und frisch vor Ort gebackenem Brot besteht.<\/p><div class=\"flex flex-grow flex-col max-w-full\"><div class=\"min-h-[20px] text-message flex flex-col items-start whitespace-pre-wrap break-words [.text-message+&amp;]:mt-5 juice:w-full juice:items-end overflow-x-auto gap-2\" dir=\"auto\" data-message-author-role=\"assistant\" data-message-id=\"a3251fb3-e8c9-4453-984a-571e9dd55f0b\"><div class=\"flex w-full flex-col gap-1 juice:empty:hidden juice:first:pt-[3px]\"><div class=\"markdown prose w-full break-words dark:prose-invert dark\"><p><span style=\"text-decoration: underline; color: #000000;\"><strong>Fr\u00fchst\u00fcck:<\/strong><\/span> Wachen Sie mit einer Auswahl an authentischen Speisen auf: frisches Pitabrot, cremiges Labneh, herzhaftes Za'atar und knusprige Falafel. Servieren Sie dazu Quark, lokale Oliven und frisches Gem\u00fcse wie Tomaten und Gurken.<\/p><p>Genie\u00dfen Sie auch Eier, die auf beduinische Art zubereitet werden. Als Getr\u00e4nke bieten wir duftenden Pfefferminztee und traditionellen Beduinenkaffee an, der oft mit Kardamom verfeinert wird. Dieses reichhaltige und schmackhafte Fr\u00fchst\u00fcck, das in der ruhigen Atmosph\u00e4re der Wadi Rum-W\u00fcste serviert wird, wird Ihnen die n\u00f6tige Energie f\u00fcr einen Tag voller Abenteuer und Entdeckungen geben.<\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" id=\"e-n-tab-content-1656952145\" role=\"tabpanel\" aria-labelledby=\"e-n-tab-title-1656952145\" data-tab-index=\"5\" style=\"--n-tabs-title-order: 5;\" class=\"elementor-element elementor-element-822a80c e-con-full e-flex e-con e-child\" data-id=\"822a80c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-2beea4d e-con-full e-flex e-con e-child\" data-id=\"2beea4d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cd3844b elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"cd3844b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Bild Karussell\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 von 12\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/wadirumdune.com\/wp-content\/uploads\/2024\/05\/Imaujujuge_Editor4.jpg\" alt=\"Imaujujuge_Editor(4)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 von 12\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/wadirumdune.com\/wp-content\/uploads\/2024\/10\/Image_Editor-1-1.jpg\" alt=\"Image_Editor (1)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 von 12\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/wadirumdune.com\/wp-content\/uploads\/2024\/10\/Image_Editor-2.jpg\" alt=\"Image_Editor (2)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 von 12\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/wadirumdune.com\/wp-content\/uploads\/2024\/10\/Image_Editor.jpg\" alt=\"Image_Editor\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 von 12\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/wadirumdune.com\/wp-content\/uploads\/2024\/05\/Image_Editor-3.jpg\" alt=\"Image_Editor (3)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 von 12\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/wadirumdune.com\/wp-content\/uploads\/2024\/05\/Cropped_Image-4.jpg\" alt=\"Cropped_Image (4)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 von 12\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/wadirumdune.com\/wp-content\/uploads\/2024\/05\/Cropped_Image-3.jpg\" alt=\"Cropped_Image (3)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 von 12\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/wadirumdune.com\/wp-content\/uploads\/2024\/05\/Cropped_Image-6.jpg\" alt=\"Cropped_Image (6)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 von 12\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/wadirumdune.com\/wp-content\/uploads\/2024\/05\/Cropped_Image-7.jpg\" alt=\"Cropped_Image (7)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 von 12\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/wadirumdune.com\/wp-content\/uploads\/2024\/05\/Image_Editor-7.jpg\" alt=\"Image_Editor (7)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"11 von 12\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/wadirumdune.com\/wp-content\/uploads\/2024\/05\/Image_Editor-16.jpg\" alt=\"Image_Editor (16)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"12 von 12\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/wadirumdune.com\/wp-content\/uploads\/2024\/05\/Image_Editor3.jpg\" alt=\"Image_Editor(3)\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-13f7069 e-con-full e-flex e-con e-child\" data-id=\"13f7069\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a15b3c5 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"a15b3c5\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Entdecken Sie den Charme und die Authentizit\u00e4t unserer Mietzelte im Herzen der W\u00fcste von Wadi Rum. Unsere Zelte aus Ziegenhaar sind so konzipiert, dass sie optimalen Komfort bieten und gleichzeitig die Traditionen der Beduinen respektieren. Sie lassen Sie in eine einzigartige und immersive Erfahrung eintauchen.<\/p><p>Jedes Zelt ist ger\u00e4umig und privat, mit bequemen Betten mit frischen Laken und warmen Decken ausgestattet. Ausgestattet mit Innenbeleuchtung, erm\u00f6glichen sie zu jeder Tageszeit einen bequemen Aufenthalt. Wir bieten Doppel-, Dreifach- und Familienzelte an, die f\u00fcr verschiedene Gruppen und Konstellationen geeignet sind.<\/p><p>Unsere Zelte stehen an sorgf\u00e4ltig ausgew\u00e4hlten Standorten und bieten einen atemberaubenden Blick auf die goldenen D\u00fcnen und die spektakul\u00e4ren Felsformationen des Wadi Rum. Wachen Sie zum Sonnenaufgang auf und schlafen Sie unter dem Sternenhimmel in einer friedlichen und bezaubernden Umgebung ein.<\/p><p>Genie\u00dfen Sie die Geselligkeit der Beduinen mit Gemeinschaftsr\u00e4umen, in denen Sie am Lagerfeuer Geschichten austauschen, traditionelle Mahlzeiten genie\u00dfen und sich nach einem Tag voller Erkundungen entspannen k\u00f6nnen. Unsere Zelte, die Sie in Wadi Rum mieten k\u00f6nnen, versprechen einen unvergesslichen Ausflug, der modernen Komfort mit dem Charme der Vorfahren verbindet.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-3bc1fd42 e-con-full e-flex e-con e-parent\" data-id=\"3bc1fd42\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-c3be596 e-flex e-con-boxed e-con e-child\" data-id=\"c3be596\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-53510b2 e-con-full e-flex e-con e-child\" data-id=\"53510b2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b1cbf38 elementor-widget elementor-widget-menu-anchor\" data-id=\"b1cbf38\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"etoile\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-58bee7f elementor-widget-divider--view-line elementor-invisible elementor-widget elementor-widget-divider\" data-id=\"58bee7f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:300}\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a1d5529 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"a1d5529\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Nacht unter dem Sternenhimmel<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6b7446a elementor-widget-divider--view-line elementor-invisible elementor-widget elementor-widget-divider\" data-id=\"6b7446a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:300}\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-6650072 e-con-full e-flex e-con e-child\" data-id=\"6650072\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-77be64c4 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"77be64c4\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-46e3508 elementor-widget elementor-widget-image\" data-id=\"46e3508\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/wadirumdune.com\/wp-content\/uploads\/2024\/06\/1287199429-1024x768.jpg\" class=\"attachment-large size-large wp-image-3334\" alt=\"\" srcset=\"https:\/\/wadirumdune.com\/wp-content\/uploads\/2024\/06\/1287199429-1024x768.jpg 1024w, https:\/\/wadirumdune.com\/wp-content\/uploads\/2024\/06\/1287199429-300x225.jpg 300w, https:\/\/wadirumdune.com\/wp-content\/uploads\/2024\/06\/1287199429-768x576.jpg 768w, https:\/\/wadirumdune.com\/wp-content\/uploads\/2024\/06\/1287199429-600x450.jpg 600w, https:\/\/wadirumdune.com\/wp-content\/uploads\/2024\/06\/1287199429.jpg 1200w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-14f45286 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"14f45286\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-315a24f7 elementor-widget elementor-widget-text-editor\" data-id=\"315a24f7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Erleben Sie eine magische Nacht unter dem Sternenhimmel von Wadi Rum. Umgeben von goldenen D\u00fcnen und majest\u00e4tischen Felsformationen genie\u00dfen Sie die Ruhe der W\u00fcste und die W\u00e4rme eines Beduinenlagerfeuers. Ein unvergessliches Erlebnis unter dem Sternenhimmel.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-49f567c8 elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"49f567c8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-map-marker-alt\" viewbox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M172.268 501.67C26.97 291.031 0 269.413 0 192 0 85.961 85.961 0 192 0s192 85.961 192 192c0 77.413-26.97 99.031-172.268 309.67-9.535 13.774-29.93 13.773-39.464 0zM192 272c44.183 0 80-35.817 80-80s-35.817-80-80-80-80 35.817-80 80 35.817 80 80 80z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><span><b><font style=\"vertical-align: inherit\"><font style=\"vertical-align: inherit\">Lokalisierung:<\/font><\/font><\/b><font style=\"vertical-align: inherit\"><font style=\"vertical-align: inherit\"> <\/font><\/font><\/span><span style=\"font-size: 12pt;line-height: 107%;font-family: Oswald;background-image: initial;background-position: initial;background-size: initial;background-repeat: initial;background-attachment: initial\"> \n inmitten der W\u00fcste<\/span><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-truck-pickup\" viewbox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M624 288h-16v-64c0-17.67-14.33-32-32-32h-48L419.22 56.02A64.025 64.025 0 0 0 369.24 32H256c-17.67 0-32 14.33-32 32v128H64c-17.67 0-32 14.33-32 32v64H16c-8.84 0-16 7.16-16 16v32c0 8.84 7.16 16 16 16h49.61c-.76 5.27-1.61 10.52-1.61 16 0 61.86 50.14 112 112 112s112-50.14 112-112c0-5.48-.85-10.73-1.61-16h67.23c-.76 5.27-1.61 10.52-1.61 16 0 61.86 50.14 112 112 112s112-50.14 112-112c0-5.48-.85-10.73-1.61-16H624c8.84 0 16-7.16 16-16v-32c0-8.84-7.16-16-16-16zM288 96h81.24l76.8 96H288V96zM176 416c-26.47 0-48-21.53-48-48s21.53-48 48-48 48 21.53 48 48-21.53 48-48 48zm288 0c-26.47 0-48-21.53-48-48s21.53-48 48-48 48 21.53 48 48-21.53 48-48 48z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><span><b><font style=\"vertical-align: inherit\"><font style=\"vertical-align: inherit\">Transport <\/font><\/font><\/b><font style=\"vertical-align: inherit\"><font style=\"vertical-align: inherit\">: <\/font><\/font><\/span><span data-elementor-setting-key=\"icon_list.0.text\" data-pen-placeholder=\"\u00c9crivez ici...\"><\/span><br><span><font style=\"vertical-align: inherit\"><font style=\"vertical-align: inherit\">- <\/font><\/font><\/span><span data-elementor-setting-key=\"icon_list.5.text\" data-pen-placeholder=\"\u00c9crivez ici...\"><span style=\"font-size: 12pt;line-height: 107%;font-family: Oswald;background-image: initial;background-position: initial;background-size: initial;background-repeat: initial;background-attachment: initial\">Nach einem Ausflug werden Sie am Biwakplatz abgesetzt.<\/span><\/span><br><span><font style=\"vertical-align: inherit\"><font style=\"vertical-align: inherit\">- <\/font><\/font><\/span><span data-elementor-setting-key=\"icon_list.5.text\" data-pen-placeholder=\"\u00c9crivez ici...\"><span style=\"font-size: 12pt;color: var( --e-global-color-secondary );background-image: initial;background-position: initial;background-size: initial;background-repeat: initial;background-attachment: initial;line-height: 107%;font-family: Oswald\">Andernfalls holen wir Sie im Dorf Wadi Rum ab.<\/span><\/span><span><font style=\"vertical-align: inherit\"><font style=\"vertical-align: inherit\">.<\/font><\/font><\/span><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-shower\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M304,320a16,16,0,1,0,16,16A16,16,0,0,0,304,320Zm32-96a16,16,0,1,0,16,16A16,16,0,0,0,336,224Zm32,64a16,16,0,1,0-16-16A16,16,0,0,0,368,288Zm-32,32a16,16,0,1,0-16-16A16,16,0,0,0,336,320Zm-32-64a16,16,0,1,0,16,16A16,16,0,0,0,304,256Zm128-32a16,16,0,1,0-16-16A16,16,0,0,0,432,224Zm-48,16a16,16,0,1,0,16-16A16,16,0,0,0,384,240Zm-16-48a16,16,0,1,0,16,16A16,16,0,0,0,368,192Zm96,32a16,16,0,1,0,16,16A16,16,0,0,0,464,224Zm32-32a16,16,0,1,0,16,16A16,16,0,0,0,496,192Zm-64,64a16,16,0,1,0,16,16A16,16,0,0,0,432,256Zm-32,32a16,16,0,1,0,16,16A16,16,0,0,0,400,288Zm-64,64a16,16,0,1,0,16,16A16,16,0,0,0,336,352Zm-32,32a16,16,0,1,0,16,16A16,16,0,0,0,304,384Zm64-64a16,16,0,1,0,16,16A16,16,0,0,0,368,320Zm21.65-218.35-11.3-11.31a16,16,0,0,0-22.63,0L350.05,96A111.19,111.19,0,0,0,272,64c-19.24,0-37.08,5.3-52.9,13.85l-10-10A121.72,121.72,0,0,0,123.44,32C55.49,31.5,0,92.91,0,160.85V464a16,16,0,0,0,16,16H48a16,16,0,0,0,16-16V158.4c0-30.15,21-58.2,51-61.93a58.38,58.38,0,0,1,48.93,16.67l10,10C165.3,138.92,160,156.76,160,176a111.23,111.23,0,0,0,32,78.05l-5.66,5.67a16,16,0,0,0,0,22.62l11.3,11.31a16,16,0,0,0,22.63,0L389.65,124.28A16,16,0,0,0,389.65,101.65Z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><span><b><font style=\"vertical-align: inherit\"><font style=\"vertical-align: inherit\">Badezimmer\/WC :<\/font><\/font><\/b><font style=\"vertical-align: inherit\"><font style=\"vertical-align: inherit\"> <\/font><\/font><\/span><span style=\"font-size: 12pt;line-height: 107%;font-family: Oswald;background-image: initial;background-position: initial;background-size: initial;background-repeat: initial;background-attachment: initial\">Keine Toilette oder Dusche<\/span><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-utensils\" viewbox=\"0 0 416 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.9 15.2c.8 4.7 16.1 94.5 16.1 128.8 0 52.3-27.8 89.6-68.9 104.6L168 486.7c.7 13.7-10.2 25.3-24 25.3H80c-13.7 0-24.7-11.5-24-25.3l12.9-238.1C27.7 233.6 0 196.2 0 144 0 109.6 15.3 19.9 16.1 15.2 19.3-5.1 61.4-5.4 64 16.3v141.2c1.3 3.4 15.1 3.2 16 0 1.4-25.3 7.9-139.2 8-141.8 3.3-20.8 44.7-20.8 47.9 0 .2 2.7 6.6 116.5 8 141.8.9 3.2 14.8 3.4 16 0V16.3c2.6-21.6 44.8-21.4 48-1.1zm119.2 285.7l-15 185.1c-1.2 14 9.9 26 23.9 26h56c13.3 0 24-10.7 24-24V24c0-13.2-10.7-24-24-24-82.5 0-221.4 178.5-64.9 300.9z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><span><b><font style=\"vertical-align: inherit\"><font style=\"vertical-align: inherit\">Essen:<\/font><\/font><\/b><\/span><span style=\"font-size: 12pt;line-height: 107%;font-family: Oswald;background-image: initial;background-position: initial;background-size: initial;background-repeat: initial;background-attachment: initial\"> Halbpension Ein Beduinen-Abendessen und ein Fr\u00fchst\u00fcck sind in unserem Service inbegriffen <\/span><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plug\" viewbox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M320,32a32,32,0,0,0-64,0v96h64Zm48,128H16A16,16,0,0,0,0,176v32a16,16,0,0,0,16,16H32v32A160.07,160.07,0,0,0,160,412.8V512h64V412.8A160.07,160.07,0,0,0,352,256V224h16a16,16,0,0,0,16-16V176A16,16,0,0,0,368,160ZM128,32a32,32,0,0,0-64,0v96h64Z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><span><b><font style=\"vertical-align: inherit\"><font style=\"vertical-align: inherit\">Ausstattung :<\/font><\/font><\/b> <\/span><span style=\"font-size: 12pt;line-height: 107%;font-family: Oswald;background-image: initial;background-position: initial;background-size: initial;background-repeat: initial;background-attachment: initial\">Kein Strom<\/span><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-70cfb4a e-con-full e-flex e-con e-child\" data-id=\"70cfb4a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-78779c7 elementor-widget-divider--view-line_text elementor-widget-divider--element-align-center elementor-invisible elementor-widget elementor-widget-divider\" data-id=\"78779c7\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:300}\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t\t<span class=\"elementor-divider__text elementor-divider__element\">\n\t\t\t\tTarife\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-827f979 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"827f979\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-596cdba e-con-full e-flex e-con e-child\" data-id=\"596cdba\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<a class=\"eael-wrapper-link-cb420ed --eael-wrapper-link-tag\" href=\"https:\/\/wadirumdune.com\/de\/reservierung\/\"><\/a>\t\t<div data-eael-wrapper-link=\"eael-wrapper-link-cb420ed\" class=\"elementor-element elementor-element-cb420ed elementor-widget__width-inherit e-transform elementor-widget elementor-widget-price-table\" data-id=\"cb420ed\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_transform_translateY_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:-7,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"price-table.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"elementor-price-table\">\n\t\t\t\t\t\t\t<div class=\"elementor-price-table__header\">\n\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-price-table__heading\">\n\t\t\t\t\t\t1+ Erwachsener\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<div class=\"elementor-price-table__price\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-price-table__integer-part\">\n\t\t\t\t\t\t25\t\t\t\t\t<\/span>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-price-table__after-price\">\n\t\t\t\t\t\t<span class=\"elementor-price-table__fractional-part\">\n\t\t\t\t\t\t\tJOD\t\t\t\t\t\t<\/span>\n\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-price-table__period elementor-typo-excluded\">Pro Erwachsener<\/span>\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<ul class=\"elementor-price-table__features-list\">\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"elementor-repeater-item-cfbdd81\">\n\t\t\t\t\t\t\t<div class=\"elementor-price-table__feature-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t&nbsp;\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-d759269 e-con-full e-flex e-con e-child\" data-id=\"d759269\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<a class=\"eael-wrapper-link-ea9a403 --eael-wrapper-link-tag\" href=\"https:\/\/wadirumdune.com\/de\/kontakt\/\"><\/a>\t\t<div data-eael-wrapper-link=\"eael-wrapper-link-ea9a403\" class=\"elementor-element elementor-element-ea9a403 elementor-widget__width-inherit e-transform elementor-widget elementor-widget-price-table\" data-id=\"ea9a403\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_transform_translateY_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:-7,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"price-table.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"elementor-price-table\">\n\t\t\t\t\t\t\t<div class=\"elementor-price-table__header\">\n\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-price-table__heading\">\n\t\t\t\t\t\tNach Kostenvoranschlag\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<div class=\"elementor-price-table__price\">\n\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<ul class=\"elementor-price-table__features-list\">\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"elementor-repeater-item-898e567\">\n\t\t\t\t\t\t\t<div class=\"elementor-price-table__feature-inner\">\n\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"feather icon-check-circle\"><\/i>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span >\n\t\t\t\t\t\t\t\t\t\t8+ Erwachsene\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"elementor-repeater-item-cfbdd81\">\n\t\t\t\t\t\t\t<div class=\"elementor-price-table__feature-inner\">\n\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"feather icon-check-circle\"><\/i>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span >\n\t\t\t\t\t\t\t\t\t\tAusfl\u00fcge, die l\u00e4nger als 4 Tage dauern\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>WADI RUM DUNE Tours &amp; Camp Votre aventure b\u00e9douine commence ici R\u00e9server votre exp\u00e9rience Nuit dans le d\u00e9sert Nuit au Camp Dormez sous les \u00e9toiles du d\u00e9sert de Wadi Rum dans notre Camp. Profitez du confort et de l&rsquo;authenticit\u00e9 de nos tentes b\u00e9douines en savoir plus Nuit \u00e0 la belle \u00e9toile Vivez une nuit magique [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-34","page","type-page","status-publish","hentry"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/wadirumdune.com\/de\/wp-json\/wp\/v2\/pages\/34","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wadirumdune.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/wadirumdune.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/wadirumdune.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wadirumdune.com\/de\/wp-json\/wp\/v2\/comments?post=34"}],"version-history":[{"count":12,"href":"https:\/\/wadirumdune.com\/de\/wp-json\/wp\/v2\/pages\/34\/revisions"}],"predecessor-version":[{"id":5468,"href":"https:\/\/wadirumdune.com\/de\/wp-json\/wp\/v2\/pages\/34\/revisions\/5468"}],"wp:attachment":[{"href":"https:\/\/wadirumdune.com\/de\/wp-json\/wp\/v2\/media?parent=34"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}